{"id":5589,"date":"2024-11-11T16:10:14","date_gmt":"2024-11-11T14:10:14","guid":{"rendered":"https:\/\/seawings.es\/?post_type=for-sale&#038;p=5589"},"modified":"2024-11-11T16:10:14","modified_gmt":"2024-11-11T14:10:14","slug":"new-apartment-oasis-golf-in-algorfa","status":"publish","type":"for-sale","link":"https:\/\/seawings.es\/en\/for-sale\/new-apartment-oasis-golf-in-algorfa\/","title":{"rendered":"New apartment &#8211; Oasis Golf in Algorfa"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>LOCATION<\/strong>: Algorfa, Alicante, Spain<\/p>\n<p style=\"font-weight: 400;\"><strong>STATUS:<\/strong> Under Development<\/p>\n<p style=\"font-weight: 400;\"><strong>EXPECTED COMPLETION DATE:<\/strong> End of 2025<\/p>\n<hr \/>\n<p style=\"font-weight: 400;\">Welcome to your new home in the heart of La Finca Golf in Algorfa: We are pleased to present our new and exclusive residential complex of 40 apartments that combines luxury, comfort, and nature in one place. With options of 2 or 3 bedrooms, these apartments offer the flexibility you need to tailor your space to your needs. You can choose between the comfort of a ground floor with a private garden or an upper floor with a private solarium, perfect for enjoying the incredible views of the golf course.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">This residential complex features a spectacular communal pool, perfect for relaxation, as well as children\u2019s play areas, a p\u00e9tanque area, and a mini-golf area to<\/p>\n<p style=\"font-weight: 400;\">enjoy the sunny days and the Costa Blanca climate. Surrounded by nature and with panoramic views of the golf course, every corner is designed to maximize comfort and exclusivity. Every detail has been carefully selected to offer an unmatched lifestyle, combining luxury, comfort, and innovative design in every<\/p>\n<p style=\"font-weight: 400;\">corner, while staying true to our identity of offering homes finished with unbeatable quality and fully equipped.<\/p>\n<p style=\"font-weight: 400;\">\n<hr \/>\n<p style=\"font-weight: 400;\">The building will be executed in compliance with all existing regulations on Basic Building Standards and special regulations.<\/p>\n<p style=\"font-weight: 400;\">\n<ul style=\"font-weight: 400;\">\n<li>FOUNDATION.- It will be carried out using slab, tie beams, and foundation walls.<\/li>\n<li>STRUCTURE.- Unidirectional slabs throughout the building.<\/li>\n<li>EXTERIOR ENCLOSURES.- Ceramic enclosures with thermal-acoustic insulation.<\/li>\n<li>FACADES.- Exterior treatment with monocapa materials painted in white and black colour.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">PARKING AREA:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Surface parking area next to the homes with access near the street.<\/li>\n<li>Access from the parking lot to the homes via a common corridor.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">COMMON AREA:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>LEISURE AREA:<br \/>\no The community floor will be equipped with a green area comprising a pool with a children\u2019s zone,<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">adult area, shower, pe\u0301tanque area, spacious children\u2019s play areas, an outdoor gym, and mini-golf.<\/p>\n<p style=\"font-weight: 400;\">\n<ul style=\"font-weight: 400;\">\n<li>HOUSING ACCESS:<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">o Access to the homes from common corridors from the street and through common areas. o Gated development.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">FLOORING:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>INTERIOR STAIRS:<br \/>\no Anti-slip ceramic tile flooring, first quality.<\/li>\n<li>EXTERIOR STAIRS AND TERRACES:<br \/>\no Anti-slip ceramic tile flooring, first quality.<\/li>\n<li>ROOMS IN THE HOME:<br \/>\no First-quality ceramic tile flooring in all rooms.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">TILING:<\/p>\n<ul>\n<li style=\"font-weight: 400;\">Ceramic tile wall covering, first quality in bathrooms.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">FALSE CEILINGS:<\/p>\n<ul>\n<li style=\"font-weight: 400;\">False plasterboard ceilings for painting in bathrooms and in any room deemed appropriate by the site management due to installation requirements.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">EXTERIOR CARPENTRY:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Sliding windows in high-quality matte black aluminum R9111 with thermal break.<\/li>\n<li>Motorized aluminum blinds in the same color, MONOBLOC type.<\/li>\n<li>Low-emissivity double glazing with argon gas chamber.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">INTERIOR CARPENTRY:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Entrance door to the home in matte black aluminum R9111 with three security points, knob, and peephole.<\/li>\n<li>Interior passage doors in smooth white lacquered wood with 7 cm trim.<\/li>\n<li>Built-in wardrobes in bedrooms finished in wood, with a top shelf, hanging bar, and drawers.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">FURNITURE:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Fully furnished home with first-quality furniture.<\/li>\n<li>Appliances included.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">KITCHEN:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>High-quality kitchen furniture with upper and lower cabinets.<\/li>\n<li>Integrated extractor hood.<\/li>\n<li>Porcelain countertop by Coverlam, Paladio model.<\/li>\n<li>Stainless steel sink.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">BATHROOMS:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Cold and hot water installation according to NT-BE-IFC Standards with PPR piping. Hot water pipes insulated to prevent heat loss.<\/li>\n<li>Premium single-lever faucets with integrated ceiling shower.<\/li>\n<li>Mechanical ventilation installation.<\/li>\n<li>White vitrified porcelain sanitaryware with matching toilet seat cover.<\/li>\n<li>Shower tray integrated with the same flooring as the home.<\/li>\n<li>Shower screens and bathroom furniture.<\/li>\n<li>Bathroom mirror with LED light.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">SOLARIUM:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Terrace made with concrete slopes, waterproof insulation, and ceramic flooring.<\/li>\n<li>Water and light points.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">PAINTING:<\/p>\n<ul>\n<li style=\"font-weight: 400;\">Smooth white paint.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">ELECTRICAL AND TELEPHONE INSTALLATION:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Electrical installation according to the new Low Voltage Regulations.<\/li>\n<li>Installation according to telecommunications standards. Telephone and TV outlets in all rooms.<\/li>\n<li>Lighting package throughout the home.<\/li>\n<li>Video intercom installation.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">OTHERS:<\/p>\n<ul>\n<li>Mailboxes installed in common areas, in accordance with the General Directorate of Postal Services for residential mailboxes.<\/li>\n<li>Installation of collective TV antenna according to Telecommunications regulations.<\/li>\n<li>Installation for hot water supply according to regulations.<\/li>\n<li>Air conditioning via ducts. Machine included.<\/li>\n<li>Electric water heater.<\/li>\n<\/ul>\n<hr \/>\n<p>Please folow our website for more objects: <a href=\"https:\/\/seawings.es\/en\/houses-for-sale\/\">https:\/\/seawings.es\/en\/houses-for-sale\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":5603,"template":"","class_list":["post-5589","for-sale","type-for-sale","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New apartment - Oasis Golf in Algorfa | Seawings<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seawings.es\/en\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New apartment - Oasis Golf in Algorfa | Seawings\" \/>\n<meta property=\"og:description\" content=\"LOCATION: Algorfa, Alicante, Spain STATUS: Under Development EXPECTED COMPLETION DATE: End of 2025 Welcome to your new home in the heart of La Finca Golf in Algorfa: We are pleased to present our new and exclusive residential complex of 40 apartments that combines luxury, comfort, and nature in one place. With options of 2 or [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seawings.es\/en\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/\" \/>\n<meta property=\"og:site_name\" content=\"Seawings\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/\",\"url\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/\",\"name\":\"New apartment - Oasis Golf in Algorfa | Seawings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seawings.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seawings.es\\\/wp-content\\\/uploads\\\/Render-Oasis-Golf-La-Finca-14-scaled.jpg\",\"datePublished\":\"2024-11-11T14:10:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seawings.es\\\/wp-content\\\/uploads\\\/Render-Oasis-Golf-La-Finca-14-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/seawings.es\\\/wp-content\\\/uploads\\\/Render-Oasis-Golf-La-Finca-14-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seawings.es\\\/fr\\\/for-sale\\\/nouvel-appartement-oasis-golf-in-algorfa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seawings.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New apartment &#8211; Oasis Golf in Algorfa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seawings.es\\\/#website\",\"url\":\"https:\\\/\\\/seawings.es\\\/\",\"name\":\"Seawings Real | Estate Property Management, Sales & Rentals in Spain\",\"description\":\"Your Gateway to Premier Properties in Spain \u2013 Buy, Rent, Manage with Confidence.\",\"publisher\":{\"@id\":\"https:\\\/\\\/seawings.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seawings.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seawings.es\\\/#organization\",\"name\":\"Seawings Real | Estate Property Management, Sales & Rentals in Spain\",\"url\":\"https:\\\/\\\/seawings.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/seawings.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seawings.es\\\/wp-content\\\/uploads\\\/Sea_wings_logo_darbinis_jpeg-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/seawings.es\\\/wp-content\\\/uploads\\\/Sea_wings_logo_darbinis_jpeg-scaled.jpg\",\"width\":2560,\"height\":1770,\"caption\":\"Seawings Real | Estate Property Management, Sales & Rentals in Spain\"},\"image\":{\"@id\":\"https:\\\/\\\/seawings.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New apartment - Oasis Golf in Algorfa | Seawings","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seawings.es\/en\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/","og_locale":"en_US","og_type":"article","og_title":"New apartment - Oasis Golf in Algorfa | Seawings","og_description":"LOCATION: Algorfa, Alicante, Spain STATUS: Under Development EXPECTED COMPLETION DATE: End of 2025 Welcome to your new home in the heart of La Finca Golf in Algorfa: We are pleased to present our new and exclusive residential complex of 40 apartments that combines luxury, comfort, and nature in one place. With options of 2 or [&hellip;]","og_url":"https:\/\/seawings.es\/en\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/","og_site_name":"Seawings","og_image":[{"width":2560,"height":1440,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/","url":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/","name":"New apartment - Oasis Golf in Algorfa | Seawings","isPartOf":{"@id":"https:\/\/seawings.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/#primaryimage"},"image":{"@id":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/#primaryimage"},"thumbnailUrl":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg","datePublished":"2024-11-11T14:10:14+00:00","breadcrumb":{"@id":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/#primaryimage","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg","contentUrl":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/seawings.es\/fr\/for-sale\/nouvel-appartement-oasis-golf-in-algorfa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seawings.es\/"},{"@type":"ListItem","position":2,"name":"New apartment &#8211; Oasis Golf in Algorfa"}]},{"@type":"WebSite","@id":"https:\/\/seawings.es\/#website","url":"https:\/\/seawings.es\/","name":"Seawings Real | Estate Property Management, Sales & Rentals in Spain","description":"Your Gateway to Premier Properties in Spain \u2013 Buy, Rent, Manage with Confidence.","publisher":{"@id":"https:\/\/seawings.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seawings.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/seawings.es\/#organization","name":"Seawings Real | Estate Property Management, Sales & Rentals in Spain","url":"https:\/\/seawings.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/seawings.es\/#\/schema\/logo\/image\/","url":"https:\/\/seawings.es\/wp-content\/uploads\/Sea_wings_logo_darbinis_jpeg-scaled.jpg","contentUrl":"https:\/\/seawings.es\/wp-content\/uploads\/Sea_wings_logo_darbinis_jpeg-scaled.jpg","width":2560,"height":1770,"caption":"Seawings Real | Estate Property Management, Sales & Rentals in Spain"},"image":{"@id":"https:\/\/seawings.es\/#\/schema\/logo\/image\/"}}]}},"meta_box":{"price":"249.000 - 295.000","price_low":"249000","price_high":"295000","bedrooms":"2 - 3","surface":"94 - 114","terrace":"27","bathrooms":"2","location":"Algorfa","ref":"AT 10308","property_type":"Apartments","type":"For sale","photos":[{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-3-scaled.jpg","filesize":830806,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-3-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":141779,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-3-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":483129,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10397,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":93209,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-3-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":326091,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-3-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":556235,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-3-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2864,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-3.jpg","ID":"5592","name":"Render-Oasis-Golf-La-Finca-3-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-3-scaled.jpg","title":"Render Oasis Golf La Finca 3","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-10-scaled.jpg","filesize":727293,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-10-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":127521,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-10-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":425745,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-10-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9265,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-10-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":84048,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-10-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":288925,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-10-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":488179,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-10-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2850,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-10.jpg","ID":"5599","name":"Render-Oasis-Golf-La-Finca-10-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-10-scaled.jpg","title":"Render Oasis Golf La Finca 10","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-13-scaled.jpg","filesize":742581,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-13-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":122289,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-13-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":425485,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-13-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8552,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-13-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":79017,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-13-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":283610,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-13-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":491415,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-13-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2855,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-13.jpg","ID":"5602","name":"Render-Oasis-Golf-La-Finca-13-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-13-scaled.jpg","title":"Render Oasis Golf La Finca 13","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-15-scaled.jpg","filesize":477906,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-15-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":99751,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-15-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":300614,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-15-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9487,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-15-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":68494,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-15-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":209509,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-15-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":337752,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-15-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2848,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-15.jpg","ID":"5604","name":"Render-Oasis-Golf-La-Finca-15-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-15-scaled.jpg","title":"Render Oasis Golf La Finca 15","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-14-scaled.jpg","filesize":745897,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-14-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":124085,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-14-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":426881,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-14-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9992,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-14-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":82184,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-14-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":285772,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-14-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":493315,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-14-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2854,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-14.jpg","ID":"5603","name":"Render-Oasis-Golf-La-Finca-14-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-14-scaled.jpg","title":"Render Oasis Golf La Finca 14","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-2-scaled.jpg","filesize":613007,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-2-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":100613,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-2-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":345194,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8831,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-2-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":66793,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-2-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":230175,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-2-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":399347,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-2-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2861,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-2.jpg","ID":"5591","name":"Render-Oasis-Golf-La-Finca-2-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2-scaled.jpg","title":"Render Oasis Golf La Finca 2","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-6-scaled.jpg","filesize":305120,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-6-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":60267,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-6-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":182442,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-6-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7743,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-6-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":42116,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-6-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":126010,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-6-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":206174,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-6-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2827,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-6.jpg","ID":"5595","name":"Render-Oasis-Golf-La-Finca-6-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-6-scaled.jpg","title":"Render Oasis Golf La Finca 6","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-4-scaled.jpg","filesize":310479,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-4-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":58478,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-4-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":183331,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7270,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-4-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":41114,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-4-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":125960,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-4-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":208824,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-4-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2844,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-4.jpg","ID":"5593","name":"Render-Oasis-Golf-La-Finca-4-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-4-scaled.jpg","title":"Render Oasis Golf La Finca 4","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-5-scaled.jpg","filesize":279575,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-5-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":55386,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-5-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":167220,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6840,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-5-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":38796,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-5-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":114807,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-5-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":188681,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-5-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2852,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-5.jpg","ID":"5594","name":"Render-Oasis-Golf-La-Finca-5-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-5-scaled.jpg","title":"Render Oasis Golf La Finca 5","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-1-scaled.jpg","filesize":259238,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-1-960x382.jpg","width":960,"height":382,"mime-type":"image\/jpeg","filesize":56695,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-960x382.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-1-1920x764.jpg","width":1920,"height":764,"mime-type":"image\/jpeg","filesize":161683,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-1920x764.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":11412,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-1-768x305.jpg","width":768,"height":305,"mime-type":"image\/jpeg","filesize":41608,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-768x305.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-1-1536x611.jpg","width":1536,"height":611,"mime-type":"image\/jpeg","filesize":114327,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-1536x611.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-1-2048x814.jpg","width":2048,"height":814,"mime-type":"image\/jpeg","filesize":178644,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-2048x814.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-1-18x7.jpg","width":18,"height":7,"mime-type":"image\/jpeg","filesize":7230,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-18x7.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-1.jpg","ID":"5590","name":"Render-Oasis-Golf-La-Finca-1-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1-scaled.jpg","title":"Render Oasis Golf La Finca 1","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-7-scaled.jpg","filesize":253443,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-7-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":47000,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-7-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":145205,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-7-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7143,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-7-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":33223,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-7-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":98538,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-7-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":166012,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-7-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2829,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-7.jpg","ID":"5596","name":"Render-Oasis-Golf-La-Finca-7-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-7-scaled.jpg","title":"Render Oasis Golf La Finca 7","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-8-scaled.jpg","filesize":276417,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-8-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":60554,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-8-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":173155,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-8-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7249,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-8-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":43002,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-8-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":123671,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-8-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":194076,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-8-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2842,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-8.jpg","ID":"5597","name":"Render-Oasis-Golf-La-Finca-8-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-8-scaled.jpg","title":"Render Oasis Golf La Finca 8","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-9-scaled.jpg","filesize":266810,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-9-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":56408,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-9-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":166106,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-9-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6610,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-9-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":39418,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-9-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":117043,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-9-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":185808,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-9-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2828,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-9.jpg","ID":"5598","name":"Render-Oasis-Golf-La-Finca-9-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-9-scaled.jpg","title":"Render Oasis Golf La Finca 9","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-17-scaled.jpg","filesize":506113,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-17-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":88070,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-17-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":292195,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-17-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8637,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-17-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":59381,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-17-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":197061,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-17-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":335649,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-17-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2868,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-17.jpg","ID":"5606","name":"Render-Oasis-Golf-La-Finca-17-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-17-scaled.jpg","title":"Render Oasis Golf La Finca 17","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-16-scaled.jpg","filesize":722488,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-16-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":116764,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-16-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":419957,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-16-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8146,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-16-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":74692,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-16-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":279646,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-16-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":484724,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-16-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2832,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-16.jpg","ID":"5605","name":"Render-Oasis-Golf-La-Finca-16-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-16-scaled.jpg","title":"Render Oasis Golf La Finca 16","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-11-scaled.jpg","filesize":511338,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-11-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":90927,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-11-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":296309,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-11-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8539,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-11-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":61557,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-11-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":200984,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-11-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":339719,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-11-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2835,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-11.jpg","ID":"5600","name":"Render-Oasis-Golf-La-Finca-11-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-11-scaled.jpg","title":"Render Oasis Golf La Finca 11","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-scaled.jpg","filesize":464088,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":82438,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":264055,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7985,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":56308,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":180226,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":303498,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2855,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca.jpg","ID":"5608","name":"Render-Oasis-Golf-La-Finca-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-scaled.jpg","title":"Render Oasis Golf La Finca","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-12-scaled.jpg","filesize":566675,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-12-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":95013,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-12-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":325157,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-12-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7965,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-12-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":63264,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-12-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":217854,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-12-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":373824,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-12-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2855,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-12.jpg","ID":"5601","name":"Render-Oasis-Golf-La-Finca-12-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-12-scaled.jpg","title":"Render Oasis Golf La Finca 12","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"Render-Oasis-Golf-La-Finca-18-scaled.jpg","filesize":572984,"sizes":{"medium":{"file":"Render-Oasis-Golf-La-Finca-18-960x540.jpg","width":960,"height":540,"mime-type":"image\/jpeg","filesize":110831,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-960x540.jpg"},"large":{"file":"Render-Oasis-Golf-La-Finca-18-1920x1080.jpg","width":1920,"height":1080,"mime-type":"image\/jpeg","filesize":342742,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-1920x1080.jpg"},"thumbnail":{"file":"Render-Oasis-Golf-La-Finca-18-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9822,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-150x150.jpg"},"medium_large":{"file":"Render-Oasis-Golf-La-Finca-18-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":75391,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-768x432.jpg"},"1536x1536":{"file":"Render-Oasis-Golf-La-Finca-18-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":236224,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-1536x864.jpg"},"2048x2048":{"file":"Render-Oasis-Golf-La-Finca-18-2048x1152.jpg","width":2048,"height":1152,"mime-type":"image\/jpeg","filesize":388299,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-2048x1152.jpg"},"trp-custom-language-flag":{"file":"Render-Oasis-Golf-La-Finca-18-18x10.jpg","width":18,"height":10,"mime-type":"image\/jpeg","filesize":2826,"url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-18x10.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Render-Oasis-Golf-La-Finca-18.jpg","ID":"5607","name":"Render-Oasis-Golf-La-Finca-18-scaled.jpg","path":"\/home\/u444898506\/domains\/seawings.es\/public_html\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-scaled.jpg","url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-150x150.jpg","full_url":"https:\/\/seawings.es\/wp-content\/uploads\/Render-Oasis-Golf-La-Finca-18-scaled.jpg","title":"Render Oasis Golf La Finca 18","caption":"","description":"","alt":"","srcset":false}],"hero_images":[{"single_image_w55drvtw0nn":"5608"},{"single_image_w55drvtw0nn":"5602"},{"single_image_w55drvtw0nn":"5595"},{"single_image_w55drvtw0nn":"5593"},{"single_image_w55drvtw0nn":"5596"},{"single_image_w55drvtw0nn":"5592"},{"single_image_w55drvtw0nn":"5591"}],"text_0flmlln6gwf7":"<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d181878.70490134615!2d-0.9376506211921928!3d38.08547573223531!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd63a449684e9701%3A0x37c7e155be98df69!2sAlgorfa%2C%20Alikant%C4%97!5e1!3m2!1slt!2ses!4v1731334173552!5m2!1slt!2ses\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>"},"_links":{"self":[{"href":"https:\/\/seawings.es\/en\/wp-json\/wp\/v2\/for-sale\/5589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seawings.es\/en\/wp-json\/wp\/v2\/for-sale"}],"about":[{"href":"https:\/\/seawings.es\/en\/wp-json\/wp\/v2\/types\/for-sale"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seawings.es\/en\/wp-json\/wp\/v2\/media\/5603"}],"wp:attachment":[{"href":"https:\/\/seawings.es\/en\/wp-json\/wp\/v2\/media?parent=5589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}